{"id":14977,"date":"2020-03-12T09:00:18","date_gmt":"2020-03-12T08:00:18","guid":{"rendered":"https:\/\/www.flyeralarm.com\/blog\/?p=14977"},"modified":"2020-03-12T08:32:36","modified_gmt":"2020-03-12T07:32:36","slug":"potencia-tu-diseno-con-iconos-y-simbolos","status":"publish","type":"post","link":"https:\/\/www.flyeralarm.com\/blog\/es\/potencia-tu-diseno-con-iconos-y-simbolos\/","title":{"rendered":"Potencia tu dise\u00f1o con iconos y s\u00edmbolos"},"content":{"rendered":"<p><span style=\"font-size: 14pt;color: #000000\"><strong>POTENCIA TU DISE\u00d1O CON ICONOS Y S\u00cdMBOLOS<\/strong><\/span><br \/>\nLa vista es una de nuestras herramientas de aprendizaje m\u00e1s valiosas y durante siglos hemos hecho uso de ella para para observar nuestros alrededores y aprender de los dem\u00e1s. Hemos desarrollado la escritura e impreso millares de libros que nos han servido como fuente de inspiraci\u00f3n y tambi\u00e9n como base de conocimiento para un sinf\u00edn de profesiones.<br \/>\nLos humanos damos m\u00e1s cr\u00e9dito a la vista que a otros sentidos. Es por eso que dicen que la vista es la primera en comer y tambi\u00e9n la primera en enamorarse.<\/p>\n<p>A lo largo de nuestra historia, hemos creado s\u00edmbolos que representan nuestras ideas, nuestras creencias y cuyos significados han trascendido durante generaciones.<\/p>\n<p>En 1963, Harvey Ball cre\u00f3 el famoso s\u00edmbolo amarillo de la cara sonriente que todos conocemos. Cre\u00f3 aquel famoso s\u00edmbolo por encargo y recibi\u00f3 45 d\u00f3lares americanos a cambio.<br \/>\nLa intenci\u00f3n que ten\u00eda la carita sonriente no era otra que animar a los trabajadores de una empresa, \u00bfpero qui\u00e9n le iba a decir a Harvey que su dise\u00f1o iba a convertirse en una de las im\u00e1genes m\u00e1s importantes del mundo para expresar emociones?<br \/>\nPodr\u00edamos en cierto modo decir que Harvey fue el inventor de los emoticonos.<\/p>\n<p>En la actualidad, podr\u00eda decirse que vivimos en la era de la comunicaci\u00f3n y pr\u00e1cticamente todos hacemos uso de m\u00e1s de una docena de emoticonos (como el que creo Harvey) a diario en aplicaciones digitales.<\/p>\n<p>Las famosas aplicaciones de mensajer\u00eda instant\u00e1nea nos permiten abreviar textos y transmitir emociones con cientos de iconos. La mayor\u00eda de nosotros hacemos uso de ellos a diario con total normalidad y tenemos incluso nuestros emoticonos favoritos.<\/p>\n<p>Pero los emoticonos no son los \u00fanicos s\u00edmbolos que reconocemos con facilidad. Tambi\u00e9n se han instalado en nuestro d\u00eda a d\u00eda, otro tipo iconos universales que nos sirven de gu\u00eda visual.<br \/>\nIconos tales como, la t\u00edpica herramienta que hace referencia al men\u00fa de ajustes dentro cualquier plataforma digital o el icono del pulgar que apunta hacia arriba, que usamos para mostrar nuestra aprobaci\u00f3n. Otro icono que reconocemos f\u00e1cilmente es el de compartir contenido.<\/p>\n<p>Los s\u00edmbolos son f\u00e1ciles de memorizar y adem\u00e1s nos ahorran tiempo de lectura.<br \/>\nPero no solo pueden utilizarse dentro de aplicaciones inform\u00e1ticas. Tambi\u00e9n sirven para sustituir textos en presentaciones y soportes impresos.<\/p>\n<p>Hace a\u00f1os que el s\u00edmbolo del tel\u00e9fono sustituye la palabra \u201ctel\u00e9fono\u201d sobre todo en <a href=\"https:\/\/www.flyeralarm.com\/es\/content\/index\/open\/id\/2917\/tarjetas-de-visita.html\">tarjetas de visitas<\/a>. Otro s\u00edmbolo que se emplea com\u00fanmente es el del sobre para representar la palabra \u201ccorreo electr\u00f3nico\u201d.<br \/>\nAmbos s\u00edmbolos llevan imprimi\u00e9ndose desde los a\u00f1os 90 y en la actualidad son solo una peque\u00f1a parte de los iconos que empleamos a diario en nuestra comunicaci\u00f3n cotidiana.<\/p>\n<p>Otros iconos que empleamos a menudo, son, por ejemplo, la bola del mundo para referirnos a \u201cp\u00e1gina web\u201d y el icono de la ubicaci\u00f3n, en lugar de la palabra \u201cdirecci\u00f3n\u201d.<br \/>\nTambi\u00e9n vemos frecuentemente, iconos de aplicaciones de mensajer\u00eda instant\u00e1nea y de redes sociales.<\/p>\n<p>Asumimos que todo el mundo conoce su significado y haciendo uso de dichos iconos, evitamos contaminar el espacio visual de nuestro dise\u00f1o de forma innecesaria.<\/p>\n<p>En el mundo corporativo es com\u00fan incluir s\u00edmbolos propios dentro del manual de identidad de marca. Estos s\u00edmbolos se pueden emplear para sustituir el nombre de servicios o de productos.<\/p>\n<p>Tambi\u00e9n es com\u00fan el uso de s\u00edmbolos en <a href=\"https:\/\/www.flyeralarm.com\/es\/content\/index\/open\/id\/2952\/cartas-de-menus.html\">cartas de men\u00fas de restaurantes<\/a>. Estos sirven para indicar que un plato contiene gluten o picante, por ejemplo.<\/p>\n<p>Te recomendamos simplificar tus textos al m\u00e1ximo posible, al <a href=\"https:\/\/www.flyeralarm.com\/es\/content\/index\/open\/id\/3248\/soportes-publicitarios.html\">imprimir soportes publicitarios<\/a>. Las personas somos cada vez m\u00e1s impacientes y agradecemos que nos simplifiquen toda la informaci\u00f3n al m\u00e1ximo posible, sobre todo si tenemos que leer instrucciones.<\/p>\n<p>Te recomendamos simplificar tus textos al m\u00e1ximo posible, al <a href=\"https:\/\/www.flyeralarm.com\/es\/content\/index\/open\/id\/3248\/soportes-publicitarios.html\">imprimir soportes publicitarios<\/a>. Las personas somos cada vez m\u00e1s impacientes y agradecemos que nos simplifiquen toda la informaci\u00f3n al m\u00e1ximo posible, sobre todo si tenemos que leer instrucciones.<\/p>\n<p>Potencia tu dise\u00f1o con iconos y s\u00edmbolos y mejora tu comunicaci\u00f3n visual.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>POTENCIA TU DISE\u00d1O CON ICONOS Y S\u00cdMBOLOS La vista es una de nuestras herramientas de aprendizaje m\u00e1s valiosas y durante siglos hemos hecho uso de ella para para observar nuestros alrededores y aprender de los dem\u00e1s. Hemos desarrollado la escritura e impreso millares de libros que nos han servido como&#8230;<\/p>\n","protected":false},"author":54,"featured_media":14978,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2325],"tags":[2975,2496],"class_list":{"0":"post-14977","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-beinspired-es","8":"tag-diseno-grafico","9":"tag-publicidad"},"acf":[],"_links":{"self":[{"href":"https:\/\/www.flyeralarm.com\/blog\/es\/wp-json\/wp\/v2\/posts\/14977","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.flyeralarm.com\/blog\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.flyeralarm.com\/blog\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.flyeralarm.com\/blog\/es\/wp-json\/wp\/v2\/users\/54"}],"replies":[{"embeddable":true,"href":"https:\/\/www.flyeralarm.com\/blog\/es\/wp-json\/wp\/v2\/comments?post=14977"}],"version-history":[{"count":0,"href":"https:\/\/www.flyeralarm.com\/blog\/es\/wp-json\/wp\/v2\/posts\/14977\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.flyeralarm.com\/blog\/es\/wp-json\/wp\/v2\/media\/14978"}],"wp:attachment":[{"href":"https:\/\/www.flyeralarm.com\/blog\/es\/wp-json\/wp\/v2\/media?parent=14977"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.flyeralarm.com\/blog\/es\/wp-json\/wp\/v2\/categories?post=14977"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.flyeralarm.com\/blog\/es\/wp-json\/wp\/v2\/tags?post=14977"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}